{"id":3629,"date":"2019-08-02T15:42:37","date_gmt":"2019-08-02T13:42:37","guid":{"rendered":"http:\/\/bachchoral.testserver-webdesigndoerrer.de\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/"},"modified":"2019-09-24T00:26:18","modified_gmt":"2019-09-23T22:26:18","slug":"mein-auge-schliess-ich-jetzt-in-gottes-namen-zu","status":"publish","type":"product","link":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/","title":{"rendered":"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-3629-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/wav\" src=\"https:\/\/www.bachchoral.de\/wp-content\/uploads\/2019\/08\/BWV-378_Mein-Augen-schlie\u00df-ich-jetzt-in-Gottes-Namen_P.wav?_=1\" \/><a href=\"https:\/\/www.bachchoral.de\/wp-content\/uploads\/2019\/08\/BWV-378_Mein-Augen-schlie\u00df-ich-jetzt-in-Gottes-Namen_P.wav\">https:\/\/www.bachchoral.de\/wp-content\/uploads\/2019\/08\/BWV-378_Mein-Augen-schlie\u00df-ich-jetzt-in-Gottes-Namen_P.wav<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[],"product_cat":[49],"product_tag":[],"class_list":{"0":"post-3629","1":"product","2":"type-product","3":"status-publish","5":"product_cat-allgemein-en","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mein Auge schlie\u00df ich jetzt in Gottes Namen zu - abc Analyse Bach-Chor\u00e4le<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu - abc Analyse Bach-Chor\u00e4le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/\" \/>\n<meta property=\"og:site_name\" content=\"abc Analyse Bach-Chor\u00e4le\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-23T22:26:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/produkt\\\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\\\/\",\"url\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/produkt\\\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\\\/\",\"name\":\"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu - abc Analyse Bach-Chor\u00e4le\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/#website\"},\"datePublished\":\"2019-08-02T13:42:37+00:00\",\"dateModified\":\"2019-09-23T22:26:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/produkt\\\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/produkt\\\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/produkt\\\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/\",\"name\":\"abc Analyse Bach-Chor\u00e4le\",\"description\":\"abc Analyse Bach-Chor\u00e4le\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bachchoral.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu - abc Analyse Bach-Chor\u00e4le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/","og_locale":"en_US","og_type":"article","og_title":"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu - abc Analyse Bach-Chor\u00e4le","og_url":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/","og_site_name":"abc Analyse Bach-Chor\u00e4le","article_modified_time":"2019-09-23T22:26:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/","url":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/","name":"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu - abc Analyse Bach-Chor\u00e4le","isPartOf":{"@id":"https:\/\/www.bachchoral.de\/en\/#website"},"datePublished":"2019-08-02T13:42:37+00:00","dateModified":"2019-09-23T22:26:18+00:00","breadcrumb":{"@id":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bachchoral.de\/en\/produkt\/mein-auge-schliess-ich-jetzt-in-gottes-namen-zu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bachchoral.de\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.bachchoral.de\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Mein Auge schlie\u00df ich jetzt in Gottes Namen zu"}]},{"@type":"WebSite","@id":"https:\/\/www.bachchoral.de\/en\/#website","url":"https:\/\/www.bachchoral.de\/en\/","name":"abc Analyse Bach-Chor\u00e4le","description":"abc Analyse Bach-Chor\u00e4le","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bachchoral.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/product\/3629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/media?parent=3629"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/product_brand?post=3629"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/product_cat?post=3629"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bachchoral.de\/en\/wp-json\/wp\/v2\/product_tag?post=3629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}